{"id":12536,"date":"2006-12-18T10:00:20","date_gmt":"2006-12-18T01:00:20","guid":{"rendered":"http:\/\/www.cm.kyushu-u.ac.jp\/?p=31"},"modified":"2006-12-18T10:00:20","modified_gmt":"2006-12-18T01:00:20","slug":"20061218%e3%80%80%e5%85%88%e7%ab%af%e7%b4%a0%e5%ad%90%e6%9d%90%e6%96%99%e9%83%a8%e9%96%80%e3%80%80%e5%8a%a9%e6%89%8b%e5%85%ac%e5%8b%9fpdf%e3%80%80%e3%82%92%e6%8e%b2%e8%bc%89%e3%81%97%e3%81%be","status":"publish","type":"post","link":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/","title":{"rendered":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df"},"content":{"rendered":"<p>\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000<a title=\"233328yokoyama.pdf\" href=\"http:\/\/www.cm.kyushu-u.ac.jp\/wp-content\/uploads\/2007\/09\/233328yokoyama1.pdf\" target=\"_blank\" rel=\"noopener\">\u52a9\u624b\u516c\u52dfPDF<\/a>\u3000\u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52dfPDF\u3000\u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"class_list":["post-12536","post","type-post","status-publish","format-standard","hentry","category-recruitment"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"takeshi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240 - Institute for Materials Chemistry and Engineering, Kyushu Univ.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240\" \/>\n\t\t<meta property=\"og:description\" content=\"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-12-18T01:00:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-12-18T01:00:20+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IMCE.KyushuUniv\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@IMCE_KyushuUniv\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@IMCE_KyushuUniv\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#blogposting\",\"name\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580 \\u52a9\\u624b\\u516c\\u52df - \\u4e5d\\u5dde\\u5927\\u5b66\\u5148\\u5c0e\\u7269\\u8cea\\u5316\\u5b66\\u7814\\u7a76\\u6240\",\"headline\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580\\u3000\\u52a9\\u624b\\u516c\\u52df\",\"author\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/author\\\/takeshi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/_cms_dir\\\/uploads\\\/2021\\\/07\\\/img_imce_logo_512x512.png\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#articleImage\",\"width\":512,\"height\":512},\"datePublished\":\"2006-12-18T10:00:20+09:00\",\"dateModified\":\"2006-12-18T10:00:20+09:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#webpage\"},\"articleSection\":\"\\u516c\\u52df\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en#listItem\",\"position\":1,\"name\":\"\\u30db\\u30fc\\u30e0\",\"item\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/category\\\/recruitment\\\/#listItem\",\"name\":\"\\u516c\\u52df\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/category\\\/recruitment\\\/#listItem\",\"position\":2,\"name\":\"\\u516c\\u52df\",\"item\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/category\\\/recruitment\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#listItem\",\"name\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580\\u3000\\u52a9\\u624b\\u516c\\u52df\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en#listItem\",\"name\":\"\\u30db\\u30fc\\u30e0\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#listItem\",\"position\":3,\"name\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580\\u3000\\u52a9\\u624b\\u516c\\u52df\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/category\\\/recruitment\\\/#listItem\",\"name\":\"\\u516c\\u52df\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#organization\",\"name\":\"\\u4e5d\\u5dde\\u5927\\u5b66\\u5148\\u5c0e\\u7269\\u8cea\\u5316\\u5b66\\u7814\\u7a76\\u6240\",\"description\":\"Institute for Materials Chemistry and Engineering, Kyushu Univ.\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/_cms_dir\\\/uploads\\\/2021\\\/07\\\/img_imce_logo_512x512.png\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMCE.KyushuUniv\\\/\",\"https:\\\/\\\/twitter.com\\\/IMCE_KyushuUniv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/author\\\/takeshi\\\/#author\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/author\\\/takeshi\\\/\",\"name\":\"takeshi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb44161783e1441fc27f3b278e6d82d26e78f064f090105de10fe70bec495dd7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"takeshi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#webpage\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/\",\"name\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580 \\u52a9\\u624b\\u516c\\u52df - \\u4e5d\\u5dde\\u5927\\u5b66\\u5148\\u5c0e\\u7269\\u8cea\\u5316\\u5b66\\u7814\\u7a76\\u6240\",\"description\":\"\\u5148\\u7aef\\u7d20\\u5b50\\u6750\\u6599\\u90e8\\u9580 \\u52a9\\u624b\\u516c\\u52dfPDF \\u3092\\u63b2\\u8f09\\u3057\\u307e\\u3057\\u305f\\u3002\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/12536\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/author\\\/takeshi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/news\\\/author\\\/takeshi\\\/#author\"},\"datePublished\":\"2006-12-18T10:00:20+09:00\",\"dateModified\":\"2006-12-18T10:00:20+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/\",\"name\":\"\\u4e5d\\u5dde\\u5927\\u5b66\\u5148\\u5c0e\\u7269\\u8cea\\u5316\\u5b66\\u7814\\u7a76\\u6240\",\"description\":\"Institute for Materials Chemistry and Engineering, Kyushu Univ.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cm.kyushu-u.ac.jp\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","description":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002","canonical_url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#blogposting","name":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","headline":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df","author":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/author\/takeshi\/#author"},"publisher":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.cm.kyushu-u.ac.jp\/_cms_dir\/uploads\/2021\/07\/img_imce_logo_512x512.png","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#articleImage","width":512,"height":512},"datePublished":"2006-12-18T10:00:20+09:00","dateModified":"2006-12-18T10:00:20+09:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#webpage"},"isPartOf":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#webpage"},"articleSection":"\u516c\u52df"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en#listItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/www.cm.kyushu-u.ac.jp\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/#listItem","name":"\u516c\u52df"}},{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/#listItem","position":2,"name":"\u516c\u52df","item":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#listItem","name":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en#listItem","name":"\u30db\u30fc\u30e0"}},{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#listItem","position":3,"name":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df","previousItem":{"@type":"ListItem","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/#listItem","name":"\u516c\u52df"}}]},{"@type":"Organization","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#organization","name":"\u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","description":"Institute for Materials Chemistry and Engineering, Kyushu Univ.","url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.cm.kyushu-u.ac.jp\/_cms_dir\/uploads\/2021\/07\/img_imce_logo_512x512.png","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/IMCE.KyushuUniv\/","https:\/\/twitter.com\/IMCE_KyushuUniv"]},{"@type":"Person","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/author\/takeshi\/#author","url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/author\/takeshi\/","name":"takeshi","image":{"@type":"ImageObject","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bb44161783e1441fc27f3b278e6d82d26e78f064f090105de10fe70bec495dd7?s=96&d=mm&r=g","width":96,"height":96,"caption":"takeshi"}},{"@type":"WebPage","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#webpage","url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/","name":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","description":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/#breadcrumblist"},"author":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/author\/takeshi\/#author"},"creator":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/author\/takeshi\/#author"},"datePublished":"2006-12-18T10:00:20+09:00","dateModified":"2006-12-18T10:00:20+09:00"},{"@type":"WebSite","@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#website","url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/","name":"\u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","description":"Institute for Materials Chemistry and Engineering, Kyushu Univ.","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"\u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240 - Institute for Materials Chemistry and Engineering, Kyushu Univ.","og:type":"article","og:title":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","og:description":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002","og:url":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/","article:published_time":"2006-12-18T01:00:20+00:00","article:modified_time":"2006-12-18T01:00:20+00:00","article:publisher":"https:\/\/www.facebook.com\/IMCE.KyushuUniv\/","twitter:card":"summary","twitter:site":"@IMCE_KyushuUniv","twitter:title":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52df - \u4e5d\u5dde\u5927\u5b66\u5148\u5c0e\u7269\u8cea\u5316\u5b66\u7814\u7a76\u6240","twitter:description":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580 \u52a9\u624b\u516c\u52dfPDF \u3092\u63b2\u8f09\u3057\u307e\u3057\u305f\u3002","twitter:creator":"@IMCE_KyushuUniv"},"aioseo_meta_data":{"post_id":"12536","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-16 04:07:36","updated":"2025-08-22 10:25:16","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.cm.kyushu-u.ac.jp\/en\" title=\"\u30db\u30fc\u30e0\">\u30db\u30fc\u30e0<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/\" title=\"\u516c\u52df\">\u516c\u52df<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u30db\u30fc\u30e0","link":"https:\/\/www.cm.kyushu-u.ac.jp\/en"},{"label":"\u516c\u52df","link":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/category\/recruitment\/"},{"label":"\u5148\u7aef\u7d20\u5b50\u6750\u6599\u90e8\u9580\u3000\u52a9\u624b\u516c\u52df","link":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/news\/12536\/"}],"_links":{"self":[{"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/posts\/12536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/comments?post=12536"}],"version-history":[{"count":0,"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/posts\/12536\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/media?parent=12536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/categories?post=12536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cm.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/tags?post=12536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}